{"id":11962,"date":"2022-12-05T05:00:19","date_gmt":"2022-12-05T04:00:19","guid":{"rendered":"https:\/\/www.quieryavenir.fr\/blog\/?p=11962"},"modified":"2022-12-05T05:43:44","modified_gmt":"2022-12-05T04:43:44","slug":"les-conflits-psychiques-provoques-par-la-gestion-politique-de-la-crise-sanitaire","status":"publish","type":"post","link":"https:\/\/www.quieryavenir.fr\/blog\/2022\/12\/05\/les-conflits-psychiques-provoques-par-la-gestion-politique-de-la-crise-sanitaire\/","title":{"rendered":"Les conflits psychiques provoqu\u00e9s par la gestion politique de la crise sanitaire"},"content":{"rendered":"<h1 style=\"text-align: left;\"><strong><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Pr\u00e9sentation par Laurent Mucchielli<\/span><\/span><\/strong><\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11961 aligncenter\" src=\"https:\/\/www.quieryavenir.fr\/blog\/wp-content\/uploads\/2022\/12\/Nucleaire-221202-1-300x222.jpg\" alt=\"\" width=\"385\" height=\"285\" srcset=\"https:\/\/www.quieryavenir.fr\/blog\/wp-content\/uploads\/2022\/12\/Nucleaire-221202-1-300x222.jpg 300w, https:\/\/www.quieryavenir.fr\/blog\/wp-content\/uploads\/2022\/12\/Nucleaire-221202-1.jpg 676w\" sizes=\"auto, (max-width: 385px) 100vw, 385px\" \/><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">L\u2019article qui suit, \u00e9crit par la victimologue Marielle Vicet, inaugure sur ce blog une s\u00e9rie de r\u00e9flexions portant sur les dimensions psychologiques individuelles et collectives de la crise sanitaire. L\u2019enjeu est important. Loin de la vision enchant\u00e9e des confinements et autres mesures de \u00ab\u00a0distanciation sociale\u00a0\u00bb que nous propose la propagande politico-industrielle, la r\u00e9alit\u00e9 des impacts psychosociaux de ces politiques sanitaires interpelle les chercheurs et les praticiens de la sant\u00e9 mentale, cette derni\u00e8re \u00e9tant une dimension tr\u00e8s importante de la sant\u00e9 tout court.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">En 2021, Monique Dagnaud, directrice de recherche \u00e9m\u00e9rite au CNRS (CEMS\/EHESS) a dirig\u00e9 une enqu\u00eate en partenariat avec ARTE et France Culture, dans le cadre du festival <\/span><\/span><em><a href=\"https:\/\/www.etmaintenant-lefestival.fr\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\"><u>Et maintenant\u00a0?<\/u><\/span><\/span><\/a><\/em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">. Diffus\u00e9e sur les r\u00e9seaux sociaux, cette enqu\u00eate a permis de recueillir des informations sur plus de 80\u00a0000 personnes de tous \u00e2ges. La population d\u2019enqu\u00eate ainsi constitu\u00e9e ne constitue pas un \u00e9chantillon repr\u00e9sentatif, elle surrepr\u00e9sente notamment les jeunes, les femmes, les classes moyennes et sup\u00e9rieures, les personnes dipl\u00f4m\u00e9es et celles vivant en r\u00e9gion parisienne. Les constats, r\u00e9sum\u00e9s dans <\/span><\/span><a href=\"https:\/\/www.radiofrance.fr\/franceculture\/comment-la-jeunesse-pense-le-monde-d-aujourd-hui-les-resultats-de-l-enquete-et-maintenant-3927976\" target=\"_blank\" rel=\"noopener\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\"><u>cette longue interview radiophonique<\/u><\/span><\/span><\/a><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">, n\u2019en sont pas moins importants. Il appara\u00eet notamment que les jeunes g\u00e9n\u00e9rations ont \u00e9t\u00e9 nettement plus impact\u00e9es dans leurs vies g\u00e9n\u00e9rales que les plus \u00e2g\u00e9s\u00a0: \u00ab\u00a0A la question \u00ab\u00a0<\/span><\/span><em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Qu\u2019est-ce que la crise vous a fait changer\u00a0?<\/span><\/span><\/em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">\u00ab\u00a0, 45\u202f% des plus de 55 ans r\u00e9pondent \u00ab\u00a0<\/span><\/span><em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">rien du tout<\/span><\/span><\/em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">\u00ab\u00a0, contre 32\u202f% des 25-39 ans et 27\u202f% des 18-24 ans. Ces derniers \u00e9voquent davantage une \u00e9volution des liens avec l\u2019entourage et, \u00e0 l\u2019\u00e2ge des grandes d\u00e9cisions quant \u00e0 son avenir, \u00e0 avoir chang\u00e9 de choix d\u2019\u00e9tudes. Leurs a\u00een\u00e9s ont connu des bouleversements similaires\u00a0: 32\u202f% affirment avoir abandonn\u00e9 leurs projets professionnels, 24\u202f% leur cadre de vie\u00a0\u00bb.\u00a0Derri\u00e8re la tranquillit\u00e9 apparente des <\/span><\/span><em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">baby-boomers<\/span><\/span><\/em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\"> se cache ainsi la souffrance des plus jeunes\u00a0: \u00ab\u00a0chez les 18-24 ans. 57\u202f% ont connu des probl\u00e8mes de d\u00e9prime et d\u2019anxi\u00e9t\u00e9, 45\u202f% de solitude, 42\u202f% de fatigue et de sommeil et 25\u202f% d\u2019alimentation (\u2026). Le questionnaire confirme ainsi les inqui\u00e9tudes concernant les effets psychologiques du Covid-19 exprim\u00e9es par les professionnels de sant\u00e9 lors du confinement et alors que les \u00e9tudiants devaient, pour la plupart, suivre des cours \u00e0 distance\u00a0\u00bb. L\u2019enqu\u00eate rel\u00e8ve \u00e9galement que, \u00ab\u00a0dans l\u2019\u00e9volution \u00e0 marche forc\u00e9e de la sociabilit\u00e9 \u00e0 distance et l\u2019enseignement en ligne, de nombreux jeunes, m\u00eame adeptes de culture num\u00e9rique, n\u2019y ont pas trouv\u00e9 un rempart contre le sentiment d\u2019isolement et ses cons\u00e9quences\u00a0\u00bb.\u00a0<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">En mai 2021, l\u2019OCDE publiait \u00e9galement un rapport intitul\u00e9 \u00ab\u00a0<\/span><\/span><a href=\"https:\/\/read.oecd-ilibrary.org\/view\/?ref=1099_1099618-muxbkalt4b&amp;title=Preserver-la-sante-mentale-des-jeunes-pendant-la-crise-du-COVID-19\" target=\"_blank\" rel=\"noopener\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\"><u>Pr\u00e9server la sant\u00e9 mentale des jeunes pendant la crise du COVID-19<\/u><\/span><\/span><\/a><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">\u00a0\u00bb. On y apprend que, avec ses confinements, ses fermetures des \u00e9tablissements de formation, ses mises contraintes en t\u00e9l\u00e9travail ou au ch\u00f4mage, \u00ab\u00a0la crise du COVID-19 a eu d\u2019importantes r\u00e9percussions sur la vie des jeunes (15-24 ans), et les donn\u00e9es disponibles font appara\u00eetre une mont\u00e9e alarmante des probl\u00e8mes de sant\u00e9 mentale dans cette classe d\u2019\u00e2ge. En Belgique, aux \u00c9tats-Unis et en France, les donn\u00e9es de mars 2021 montrent que la proportion de jeunes pr\u00e9sentant des sympt\u00f4mes d\u2019anxi\u00e9t\u00e9 et de d\u00e9pression \u00e9tait plus de deux fois sup\u00e9rieure \u00e0 celle indiqu\u00e9e par les donn\u00e9es les plus r\u00e9centes d\u2019avant la crise\u00a0\u00bb. En France, <a href=\"https:\/\/www.santepubliquefrance.fr\/etudes-et-enquetes\/coviprev-une-enquete-pour-suivre-l-evolution-des-comportements-et-de-la-sante-mentale-pendant-l-epidemie-de-covid-19#block-249162\" target=\"_blank\" rel=\"noopener\">l\u2019\u00e9tude \u00ab\u00a0CoviPrev\u00a0\u00bb de Sant\u00e9 Publique France<\/a> a \u00e9galement enregistr\u00e9 l\u2019augmentation de tous les indicateurs de mauvaise sant\u00e9 mentale suite aux confinements (perception globale de sa sant\u00e9, signes d\u2019\u00e9tats d\u00e9pressifs, signes d\u2019\u00e9tat anxieux, troubles du sommeil, pens\u00e9es suicidaires).<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Ces constats, qui recoupent ceux que font les professionnels sur le terrain (qu\u2019il s\u2019agisse des psychologues, des psychiatres ou encore des structures publiques ou priv\u00e9es d\u2019aides et d\u2019\u00e9coute), doivent nous interroger. Il en va notamment de l\u2019avenir de nos jeunes, qui ont \u00e9t\u00e9 les sacrifi\u00e9s d\u2019une crise g\u00e9r\u00e9e au nom de l\u2019int\u00e9r\u00eat des plus anciens.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Voici donc aujourd\u2019hui un premier texte portant sur les dimensions psychologiques, et plus pr\u00e9cis\u00e9ment victimologiques, de la dite crise sanitaire. J\u2019esp\u00e8re que d\u2019autres suivront, les propositions sont les bienvenues.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Laurent Mucchielli<\/span><\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">* * * * *<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">R\u00e9flexions sur les conflits psychiques provoqu\u00e9s par la gestion politique de la crise sanitaire<\/span><\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Marielle VICET, victimologue, est docteure en psychanalyse et psychopathologie. Sa th\u00e8se\u00a0portait sur les violences sexuelles en institution (<\/span><\/span><em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">\u00c9tudes pr\u00e9alables \u00e0 l\u2019intelligence \u00e9motionnelle face aux violences. Le r\u00f4le des \u00e9motions dans l\u2019\u00e9laboration psychique des professionnels en institution<\/span><\/span><\/em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">, Universit\u00e9 Sorbonne Paris Cit\u00e9, 2015).<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">L\u2019actualit\u00e9 et le narratif du discours anxiog\u00e8ne sur les maladies, sur l\u2019\u00e9tat de la plan\u00e8te, sur la guerre, sur l\u2019effondrement de l\u2019\u00e9conomie, sur la p\u00e9nurie d\u2019\u00e9nergie, ainsi que les mesures liberticides qui accompagnent ce discours (comme la crise sanitaire l\u2019a bien montr\u00e9), ont introduit chez une partie de la population un syst\u00e8me de d\u00e9fense et de survie. L\u2019impact psychique est probablement majeur pour les personnes qui vivent \u00e0 pr\u00e9sent dans un monde ins\u00e9cure et dans l\u2019incapacit\u00e9 d\u2019analyser et de concilier leurs conflits internes.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Violences et mensonges d\u2019\u00c9tat<\/span><\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Tout d\u2019abord, int\u00e9ressons-nous au processus \u00e0 l\u2019\u0153uvre dans cette crise qui fonde la violence \u00e9tatique et institutionnelle installant des fonctionnements dichotomiques, des harc\u00e8lements, des victimisations. C\u2019est une palette d\u2019agirs violents \u00e9tatiques qui entrave, enserre, \u00e9crase :<\/span><\/span><\/p>\n<p style=\"text-align: justify;\">\u2013 <span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">une instrumentalisation qui entretient la peur, une morbidit\u00e9 qui porte atteinte \u00e0 l\u2019int\u00e9grit\u00e9 psychique et physique jusqu\u2019aux contraintes vaccinales qui font intrusion, effraction et mutilation dans les corps.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\">\u2013 <span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">des manipulations et des mensonges d\u00e9lib\u00e9r\u00e9s dans les discours politiques et de la part d\u2019une cohorte de pseudo-scientifiques et d\u2019\u00ab\u00a0autorit\u00e9s sanitaires\u00a0\u00bb sur les masques, sur le nombre de malades, sur le nombre de morts Covid, sur le nombre et la gravit\u00e9 des effets ind\u00e9sirables li\u00e9s aux nouvelles th\u00e9rapies g\u00e9n\u00e9tiques. Par exemple, lorsqu\u2019il \u00e9tait ministre de la sant\u00e9, Olivier V\u00e9ran scandait que les injections \u00e0 ARN messager \u00e9taient absolument sans risques pour la m\u00e8re et l\u2019enfant. \u00ab\u00a0<\/span><\/span><em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Les femmes enceintes peuvent se faire vacciner contre le Covid-19 d\u00e8s le \u00ab\u00a0premier trimestre\u00a0\u00bb de grossesse\u00a0<\/span><\/span><\/em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">\u00bb disait-il lors de la s\u00e9ance de questions au gouvernement \u00e0 l\u2019Assembl\u00e9e nationale le 20 juillet 2021. De m\u00eame, le 24 novembre 2020, le pr\u00e9sident Emmanuel Macron avait annonc\u00e9\u00a0: \u00ab\u00a0<\/span><\/span><em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Je veux aussi \u00eatre clair : je ne rendrai pas la vaccination obligatoire\u00a0\u00bb.<\/span><\/span><\/em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\"> Et le 12 septembre 2021, <\/span><\/span><a href=\"https:\/\/www.vie-publique.fr\/discours\/280792-emmanuel-macron-12072021-pass-sanitaire-et-reforme-des-retraites\" target=\"_blank\" rel=\"noopener\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\"><u>il d\u00e9clarait<\/u><\/span><\/span><\/a><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\"><a href=\"https:\/\/www.vie-publique.fr\/discours\/280792-emmanuel-macron-12072021-pass-sanitaire-et-reforme-des-retraites\"> pourtant<\/a>\u00a0: \u00ab\u00a0<\/span><\/span><em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Dans un premier temps, pour les personnels soignants et non-soignants des h\u00f4pitaux, des cliniques, des maisons de retraite, des \u00e9tablissements pour personnes en situation de handicap, pour tous les professionnels ou b\u00e9n\u00e9voles qui travaillent au contact des personnes \u00e2g\u00e9es ou fragiles, y compris \u00e0 domicile, la vaccination sera rendue obligatoire sans attendre<\/span><\/span><\/em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">\u00a0\u00bb. Et le 18 d\u00e9cembre 2021, <\/span><\/span><a href=\"https:\/\/www.francetvinfo.fr\/sante\/maladie\/coronavirus\/vaccin\/covid-19-le-pass-vaccinal-est-une-forme-deguisee-dobligation-vaccinale-assume-olivier-veran_4885957.html\" target=\"_blank\" rel=\"noopener\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\"><u>Olivier V\u00e9ran avouait<\/u><\/span><\/span><\/a><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\"> en effet que \u00ab\u00a0<\/span><\/span><em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">le pass vaccinal est une forme d\u00e9guis\u00e9e d\u2019obligation vaccinale\u00a0<\/span><\/span><\/em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">\u00bb.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\">\u2013 <span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">l\u2019h\u00e9g\u00e9monie du tout s\u00e9curitaire, abus de pouvoir (menaces de sanction, contr\u00f4le par <\/span><\/span><em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">tracing<\/span><\/span><\/em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">), injonctions contradictoires, censure organis\u00e9e, discrimination en fonction du statut vaccinal, interdiction aux m\u00e9decins de prescrire, interdiction de tout d\u00e9bat sur les traitements et la gestion de la crise, d\u00e9ni de justice (non-reconnaissance de la culpabilit\u00e9 de celui qui viole la loi), utilisation de techniques de manipulation mentale\u00a0(<\/span><\/span><em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Nudges<\/span><\/span><\/em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">), mise sous secret-d\u00e9fense des d\u00e9cisions prises sur la crise par le pouvoir ex\u00e9cutif, etc.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">L\u2019intelligibilit\u00e9 des processus \u00e0 l\u2019\u0153uvre avec ce concentr\u00e9 d\u2019agirs violents et de manipulations entra\u00eenent une forme de d\u00e9viance institutionnalis\u00e9e lorsqu\u2019elle fait fi de la loi et des r\u00e8gles. Ainsi, l\u2019abus de pouvoir peut se faire perversion psychique lorsqu\u2019un auteur incarne la figure du sauveur dictant la loi et ordonnant en d\u00e9niant l\u2019alt\u00e9rit\u00e9 de l\u2019autre\u00a0; il place ainsi toute la population sous emprise et contr\u00f4le.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Comment croire qu\u2019un gouvernement se retourne contre la population\u00a0?<\/span><\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Au sein d\u2019une population, le niveau de conscience de la gravit\u00e9 des faits et des risques pour la d\u00e9mocratie est disparate. Beaucoup de personnes sont convaincues que les injections sont indispensables pour leur sant\u00e9 et celles de leurs proches, tel que martel\u00e9 par la propagande officielle, et sont dans la croyance qu\u2019il est n\u00e9cessaire de se soumettre pour sortir de cet enfermement et se prot\u00e9ger de tout risque.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Sont pr\u00e9sents des m\u00e9canismes de clivage permettant le retrait ou le d\u00e9ni des faits, entra\u00eenant une dissociation individuelle et collective de la r\u00e9alit\u00e9. Dans l\u2019incapacit\u00e9 de concilier ce conflit en raison de la charge \u00e9motionnelle li\u00e9e au stress, \u00e0 l\u2019anxi\u00e9t\u00e9 et au deuil, soumis \u00e0 la pers\u00e9cution, \u00e0 la menace, \u00e0 l\u2019intimidation, le m\u00e9canisme de d\u00e9fense sera le d\u00e9ni de la r\u00e9alit\u00e9, par exemple le refus de voir et d\u2019imaginer les intentions derri\u00e8re les mensonges d\u2019\u00c9tat et de ses repr\u00e9sentants institutionnels. En aucun cas, ces personnes ne peuvent imaginer que les repr\u00e9sentants \u00e9lus, politiques, responsables administratifs puissent opter pour de telles mesures contraignantes\u00a0sans qu\u2019il n\u2019y ait un r\u00e9el danger. De m\u00eame qu\u2019il est difficile d\u2019assumer de penser que des m\u00e9decins puissent d\u00e9roger au serment d\u2019Hippocrate qui fonde leur \u00e9thique professionnelle\u00a0(fid\u00e9lit\u00e9 \u00ab\u00a0<\/span><\/span><em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">aux lois de l\u2019honneur et de la probit\u00e9, de r\u00e9tablir, de pr\u00e9server ou de promouvoir la sant\u00e9 dans tous ses \u00e9l\u00e9ments, physiques et mentaux, individuels et sociaux [\u2026], de respecter toutes les personnes, leur autonomie et leur volont\u00e9, sans aucune discrimination selon leur \u00e9tat ou leurs convictions [\u2026], d\u2019informer\u00a0 les patients des d\u00e9cisions envisag\u00e9es, de leurs raisons et de leurs cons\u00e9quences\u2026, de ne tromper jamais leur confiance et n\u2019exploiter le pouvoir h\u00e9rit\u00e9 des circonstances pour forcer les consciences [\u2026], sans se laisser influencer par la soif du gain ou la recherche de la gloire [\u2026]<\/span><\/span><\/em><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">\u00a0\u00bb). Pour les personnes victimes d\u2019un conjoint violent, il est de l\u2019ordre de l\u2019IMPENSABLE que cette personne aim\u00e9e puisse adopter un comportement pervers. De m\u00eame, posons avec <\/span><\/span><a href=\"https:\/\/strategika.fr\/2021\/01\/05\/vaccin-pour-le-psychiatre-frederic-badel-le-gouvernement-organise-la-division-pour-regner-comme-une-secte\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\"><u>le Dr Fr\u00e9d\u00e9ric Badel<\/u><\/span><\/span><\/a><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\"> la question\u00a0: \u00ab\u00a0Comment croire qu\u2019un gouvernement d\u00e9mocratiquement \u00e9lu puisse se retourner contre son peuple ?\u00a0\u00bb.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Violences d\u2019\u00c9tat et perversion<\/span><\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Dans la perversion psychique, l\u2019alt\u00e9rit\u00e9 de l\u2019autre est d\u00e9ni\u00e9e, il devient objet d\u00e9shumanis\u00e9. De la m\u00eame mani\u00e8re, la s\u00e9rie de mesures et d\u2019abus de pouvoir qui caract\u00e9rise la gestion politique de la crise du Covid participe \u00e0 l\u2019\u00e9crasement des personnes en mettant en \u0153uvre des m\u00e9canismes de contr\u00f4le, de rationalisation, de justification, d\u2019attitudes de d\u00e9ni et d\u2019indiff\u00e9rence \u00e0 la souffrance d\u2019autrui. L\u2019ensemble des dirigeants des institutions de sant\u00e9 participent (en \u00e9valuant insuffisamment les dysfonctionnements et les dangers de toutes ces mesures) voire collaborent aux strat\u00e9gies des dirigeants et certains en tirent profit.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">En miroir, comment une personne saine et incapable de concevoir cet impensable peut-elle imaginer un tel sc\u00e9nario\u00a0de contr\u00f4le de toute une population sans avoir elle-m\u00eame \u00e9t\u00e9 confront\u00e9e au m\u00e9canisme pervers, voire l\u2019avoir d\u00e9pass\u00e9\u00a0ou l\u2019avoir finement analys\u00e9 ? Il est impensable pour la majorit\u00e9 de la population que ces dirigeants par la peur puissent porter sciemment atteinte \u00e0 la sant\u00e9 d\u2019autrui. Et pourtant, le port impos\u00e9 du masque, <\/span><\/span><a href=\"https:\/\/jamanetwork.com\/journals\/jamapediatrics\/fullarticle\/2781743\" target=\"_blank\" rel=\"noopener\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\"><u>qui provoque chez les enfants de l\u2019hypercapnie<\/u><\/span><\/span><\/a><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">, et la vaccination pr\u00e9sent\u00e9e comme le s\u00e9same obligatoire pour acc\u00e9der aux services et effectuer des d\u00e9placements, sont des moyens totalitaires inscrivant dans le cerveau des postures de soumission et de silence impos\u00e9 qui risquent de laisser des traces sur le long terme. Dans ce syst\u00e8me se m\u00ealent autoritarisme, toute-puissance, strat\u00e9gies, manipulations et emprise\u00a0sur l\u2019autre\u00a0; ces agirs fondent la violence \u00e9tatique.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">L\u2019attirance mim\u00e9tique ou le syst\u00e8me de coh\u00e9rence des neurones miroirs<\/span><\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Au niveau du conscient, nous partageons des r\u00e9f\u00e9rences socioculturelles, des croyances et des valeurs, qui vont repr\u00e9senter le support d\u2019une communication avec l\u2019autre\u00a0: un \u00e9change de conscient \u00e0 conscient. Il s\u2019agit d\u2019un jeu d\u2019interactions o\u00f9 l\u2019individu se construit son environnement en fonction de son axiome de vie, c\u2019est-\u00e0-dire qu\u2019il va vivre des situations et cr\u00e9er des exp\u00e9riences de vie en fonction des conflits psychiques qu\u2019il doit d\u00e9passer.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Un autre niveau de communication s\u2019\u00e9tablit d\u2019un inconscient \u00e0 un autre inconscient incluant le syst\u00e8me de coh\u00e9rence des neurones miroirs. Nous entrons en r\u00e9sonance avec l\u2019autre\u00a0gr\u00e2ce \u00e0 une attirance mim\u00e9tique dans la rencontre qui va correspondre \u00e0 la position existentielle de chacun d\u2019eux en lien avec leurs propres axiomes de vie. Dans cette dynamique, li\u00e9e \u00e0 l\u2019intersubjectivit\u00e9 et \u00e0 la force attractive, les sujets se rencontrent comme deux p\u00f4les d\u2019un aimant. C\u2019est-\u00e0-dire que le sujet va rencontrer cet autre en fonction des conflits psychiques qu\u2019il a \u00e0 traiter.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Dans cette confrontation majeure \u00e0 l\u2019autre vont \u00e9merger, en miroir, des conflits psychiques, vont \u00eatre pr\u00e9sentes des m\u00e9moires d\u2019\u00e9v\u00e9nements de la g\u00e9n\u00e9alogie familiale, des conflits issus de transmissions transg\u00e9n\u00e9rationnelles. Par exemple, un auteur de violences va chercher \u00e0 se connecter \u00e0 un sujet confront\u00e9 \u00e0 des conflits psychiques li\u00e9s \u00e0 une position de vuln\u00e9rabilit\u00e9\u00a0(soumission, injustice, d\u00e9valorisation, ranc\u0153ur, etc.). Il est n\u00e9cessaire que l\u2019auteur de violences soit dans une position d\u2019emprise sur l\u2019autre. La victime potentielle, \u00e0 son insu, va r\u00e9pondre positivement \u00e0 cette connexion afin d\u2019\u00eatre en r\u00e9sonance compl\u00e8te avec les conflits psychiques de l\u2019autre. La personne vuln\u00e9rable pense que cet autre qui se montre tellement s\u00fbr de lui (ou d\u2019elle) va lui apporter de la s\u00e9curit\u00e9, or c\u2019est tout l\u2019inverse. Ainsi, si un sujet a une \u00ab\u00a0valise\u00a0\u00bb de violence, il va rencontrer en miroir un(e) autre qui poss\u00e8de une \u00ab\u00a0valise\u00a0\u00bb de soumission. Ceci, gr\u00e2ce \u00e0 cette force attractive\u00a0: comme un miroir aimant\u00e9.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Dans le contexte actuel, gr\u00e2ce au syst\u00e8me miroir, les sujets vont op\u00e9rer des positions en fonction de leur propre axiome existentiel. Dans une nation, au c\u0153ur de l\u2019espace collectif s\u2019affrontent les axiomes divergents\u00a0de sujets aux agirs pervers ou de sujets aux agirs sauveteurs, induisant un syst\u00e8me d\u00e9faillant. Entre ces deux p\u00f4les extr\u00eames, d\u2019autres sujets investissent la sc\u00e8ne de mani\u00e8re plus adapt\u00e9e ou parfois plus chaotique, vivent des situations en lien avec leurs propres conflits, agissent ou subissent les \u00e9v\u00e9nements suivant l\u2019\u00e9quilibre qu\u2019ils tentent de maintenir sur l\u2019\u00e9chelle hom\u00e9ostasique.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Certains agirs\u00a0pervers peuvent \u00eatre actionn\u00e9s par une qu\u00eate majeure d\u2019\u00eatre aim\u00e9, li\u00e9e \u00e0 une carence affective grave, au v\u00e9cu d\u2019injustice et aux traumatismes v\u00e9cus dans la g\u00e9n\u00e9alogie, etc. Ces personnes vont adopter un investissement axiomatique du type \u00ab\u00a0\u00eatre aim\u00e9 \u00e0 tout prix\u00a0\u00bb, en raison d\u2019une grande immaturit\u00e9 affective. L\u2019intol\u00e9rance \u00e0 la frustration va parfois de pair avec des comportements impulsifs. L\u2019injonction est celle d\u2019obtenir le maximum de l\u2019autre\u00a0utilis\u00e9 comme objet, o\u00f9 l\u2019autre est maintenu \u00e0 distance, r\u00e9duit \u00e0 n\u00e9ant. Dans cette posture prime autoritarisme, m\u00e9pris, mensonges, d\u00e9ni de l\u2019existence de l\u2019autre, rigidit\u00e9, manipulation, comportements malveillants, d\u00e9viants. Si la s\u00e9duction peut venir masquer un d\u00e9ficit d\u2019estime de soi et des d\u00e9fenses contre l\u2019angoisse, contre un processus d\u00e9pressif, \u00e0 l\u2019extr\u00eame, dans l\u2019inaffectivit\u00e9, le sujet pervers manipulateur et destructeur peut \u00e9prouver beaucoup de jouissance dans l\u2019emprise qu\u2019il exerce sur sa victime.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Selon Genevi\u00e8ve Reichert-Pagnard, les pervers narcissiques exercent une emprise totale sur autrui, r\u00e9duisent l\u2019existence des autres au service de la leur. \u00ab\u00a0L\u2019autre est ressenti comme narcissiquement blessant, insupportable au point de \u00ab\u00a0l\u2019instrumentaliser\u00a0\u00bb, le faisant crouler sous les t\u00e2ches, les d\u00e9valorisations, les reproches, l\u2019utilisant comme un objet, en l\u2019\u00e9crasant et le d\u00e9sorganisant avec jouissance, tout en se survalorisant [\u2026], pour ne pas se retrouver en position d\u2019inf\u00e9riorit\u00e9\u00a0\u00bb. Il s\u2019agit, dans ce syst\u00e8me, d\u2019une emprise destructrice sur l\u2019autre\u00a0: manipulateur destructeur, l\u2019auteur d\u2019agirs violents \u00e9volue dans un syst\u00e8me relationnel tr\u00e8s dysfonctionnant, adopte une position de domination discr\u00e9ditant l\u2019autre, utilise infantilisation, d\u00e9valorisation, humiliation, culpabilit\u00e9 et attitudes de m\u00e9pris atteignant immanquablement autrui dans son image. Roger Dorey \u00e9voque trois versants qui sont \u00ab\u00a0l\u2019appropriation par d\u00e9possession de l\u2019Autre, la domination, et la n\u00e9cessit\u00e9 de graver son empreinte sur lui.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">&#8230;<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\">Pour en savoir plus\u00a0:<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Comic Sans MS, cursive;\"><span style=\"font-size: medium;\"><a href=\"https:\/\/qg.media\/blog\/laurent-mucchielli\/les-conflits-psychiques-provoques-par-la-gestion-politique-de-la-crise-sanitaire\/\">https:\/\/qg.media\/blog\/laurent-mucchielli\/les-conflits-psychiques-provoques-par-la-gestio<\/a> <\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00e9sentation par Laurent Mucchielli<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11962","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/www.quieryavenir.fr\/blog\/wp-json\/wp\/v2\/posts\/11962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.quieryavenir.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.quieryavenir.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.quieryavenir.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.quieryavenir.fr\/blog\/wp-json\/wp\/v2\/comments?post=11962"}],"version-history":[{"count":1,"href":"https:\/\/www.quieryavenir.fr\/blog\/wp-json\/wp\/v2\/posts\/11962\/revisions"}],"predecessor-version":[{"id":11963,"href":"https:\/\/www.quieryavenir.fr\/blog\/wp-json\/wp\/v2\/posts\/11962\/revisions\/11963"}],"wp:attachment":[{"href":"https:\/\/www.quieryavenir.fr\/blog\/wp-json\/wp\/v2\/media?parent=11962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.quieryavenir.fr\/blog\/wp-json\/wp\/v2\/categories?post=11962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.quieryavenir.fr\/blog\/wp-json\/wp\/v2\/tags?post=11962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}